﻿{"id":2522,"date":"2024-07-19T11:30:00","date_gmt":"2024-07-19T09:30:00","guid":{"rendered":"https:\/\/iicpechino.esteri.it\/gli_eventi\/archivio-eventi\/"},"modified":"2024-11-20T17:48:42","modified_gmt":"2024-11-20T16:48:42","slug":"archivio-eventi","status":"publish","type":"page","link":"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/archivio-eventi\/","title":{"rendered":"\u5f80\u671f\u6d3b\u52a8"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>\u8f93\u5165\u60a8\u7684\u641c\u7d22\u53c2\u6570                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">\u6765\u81ea<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">\u7ed9<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">\u514d\u8d39\u641c\u7d22\u5b57\u6bb5<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/archivio-eventi\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">\u663e\u793a\u7ed3\u679c<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/elvira-notari-beyond-silence-al-beijing-international-film-festival\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01\">\n                                                                                        <picture>\n                                                <source type=\"image\/webp\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.webp\">\n                                                <source type=\"image\/jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\">\n                                                <img loading=\"lazy\" decoding=\"async\" class=\"img-fluid\" width=\"179\" height=\"125\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\" alt=\"\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01\" title=\"\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01\">\n                                            <\/picture>\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Sat Apr 18 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Sat Apr 25 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/elvira-notari-beyond-silence-al-beijing-international-film-festival\/\" title=\"\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01\">\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01<\/a><\/h5>\n                            <p class=\"card-text\">\u4e2d\u610f\u7535\u5f71\u6587\u5316\u5bf9\u8bdd\uff1a\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01 \u503c\u6b64\u4e2d\u610f\u6587\u5316\u4ea4\u6d41\u6301\u7eed\u6df1\u5316\u4e4b\u9645\uff0c\u610f\u5927\u5229\u7eaa\u5f55\u7247\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u6210\u529f\u5165\u56f4\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\u201c\u771f\u5b9e\u81f3\u4e0a\u201d\u5355\u5143\uff0c\u5e76\u5c06\u5728\u5317\u4eac\u8fdb\u884c\u591a\u573a\u653e\u6620\u3002\u5f71\u7247\u4ee5\u5f71\u50cf\u4e4b\u529b\uff0c\u91cd\u73b0\u610f\u5927\u5229\u7535\u5f71\u53f2\u4e0a\u7b2c\u4e00\u4f4d\u5973\u6027\u5bfc\u6f14\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\u7684\u827a\u672f\u9057\u4ea7\u4e0e\u5386\u53f2\u5730\u4f4d\u3002 2026\u5e74\u6b63\u503c\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\u901d\u4e1680\u5468\u5e74\u3002\u4f5c\u4e3a\u610f\u5927\u5229\u65e0\u58f0\u7535\u5f71\u9ec4\u91d1\u65f6\u4ee3\u7684\u91cd\u8981\u4eba\u7269\uff0c\u5979\u4e00\u751f\u521b\u4f5c\u516d\u5341\u4f59\u90e8\u4f5c\u54c1\uff0c\u5c06\u5927\u4f17\u6587\u5316\u4e0e\u5bf9\u65e5\u5e38\u751f\u6d3b\u7684\u654f\u9510\u89c2\u5bdf\u76f8\u7ed3\u5408\uff0c\u5176\u4f5c\u54c1\u4ece\u90a3\u4e0d\u52d2\u65af\u4f20\u64ad\u81f3\u7f8e\u56fd\u201c\u5c0f\u610f\u5927\u5229\u201d\u793e\u533a\uff0c\u66fe\u6df1\u523b\u6253\u52a8\u8de8\u6587\u5316\u89c2\u4f17\u3002\u7136\u800c\uff0c\u968f\u7740\u6709\u58f0\u7535\u5f71\u7684\u5174\u8d77\u53ca\u6cd5\u897f\u65af\u65f6\u671f\u5ba1\u67e5\u5236\u5ea6\u7684\u5f71\u54cd\uff0c\u5979\u4e8e20\u4e16\u7eaa30\u5e74\u4ee3\u9000\u51fa\u5f71\u575b\uff0c\u5176\u4f5c\u54c1\u4ea6\u957f\u671f\u6e6e\u6ca1\u4e8e\u5386\u53f2\u4e4b\u4e2d\u3002\u7531\u4e8e\u53f2\u6599\u7559\u5b58\u6781\u4e3a\u6709\u9650\uff0c\u4ec5\u5b58\u5c11\u91cf\u5f71\u50cf\u4e0e\u6587\u732e\uff0c\u5979\u7684\u521b\u4f5c\u4e0e\u4eba\u751f\u957f\u671f\u672a\u88ab\u7cfb\u7edf\u8ba4\u8bc6\u3002 \u672c\u7247\u7531Valerio Ciriaci\u6267\u5bfc\uff0cIsaak Liptzin\u62c5\u4efb\u5236\u7247\uff0c\u7531awenfilms\u4e0eParallelo 41 Produzioni\u8054\u5408\u5236\u4f5c\u3002\u5f71\u7247\u66fe\u5165\u9009\u5a01\u5c3c\u65af\u7535\u5f71\u8282\u5e76\u83b7\u5f97\u56fd\u9645\u8303\u56f4\u7684\u5e7f\u6cdb\u5173\u6ce8\u3002\u7279\u522b\u611f\u8c22\u8bfa\u5854\u8389\u7ec4\u59d4\u4f1a\u4e3b\u5e2dAntonella Di Nocera\u5973\u58eb\u957f\u671f\u4ee5\u6765\u5bf9\u8bfa\u5854\u8389\u7814\u7a76\u4e0e\u63a8\u5e7f\u6240\u505a\u51fa\u7684\u91cd\u8981\u8d21\u732e\uff0c\u5979\u5728\u5f71\u50cf\u6574\u7406\u3001\u4fdd\u5b58\u53ca\u5b66\u672f\u9610\u91ca\u65b9\u9762\u53d1\u6325\u4e86\u5173\u952e\u4f5c\u7528\u3002 \u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u901a\u8fc7\u4ea4\u7ec7\u5386\u53f2\u6863\u6848\u4e0e\u5f53\u4ee3\u827a\u672f\u56de\u5e94\uff0c\u6c47\u805a\u5b66\u8005\u4e0e\u827a\u672f\u5bb6\u7684\u591a\u91cd\u89c6\u89d2\uff0c\u91cd\u6784\u8fd9\u4f4d\u7535\u5f71\u5148\u9a71\u7684\u521b\u4f5c\u8f68\u8ff9\u4e0e\u7cbe\u795e\u4e16\u754c\u3002\u8fd9\u4e0d\u4ec5\u662f\u4e00\u90e8\u4eba\u7269\u7eaa\u5f55\u7247\uff0c\u66f4\u662f\u4e00\u9879\u5173\u4e8e\u5f71\u50cf\u8bb0\u5fc6\u3001\u5973\u6027\u521b\u4f5c\u4e0e\u8de8\u65f6\u4ee3\u5bf9\u8bdd\u7684\u6587\u5316\u5b9e\u8df5\u3002 \u672c\u6b21\u5165\u56f4\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff0c\u65e8\u5728\u5411\u4e2d\u56fd\u89c2\u4f17\u4ecb\u7ecd\u8fd9\u4f4d\u610f\u5927\u5229\u7535\u5f71\u53f2\u4e0a\u7684\u91cd\u8981\u4eba\u7269\u3002\u672a\u6765\uff0c\u56f4\u7ed5\u8be5\u9879\u76ee\u8fd8\u5c06\u5728\u4e2d\u56fd\u9646\u7eed\u5c55\u5f00\u7cfb\u5217\u6587\u5316\u6d3b\u52a8\uff0c\u5305\u62ec\u4e13\u9898\u653e\u6620\u3001\u5c55\u89c8\u3001\u5b66\u672f\u7814\u7a76\u53ca\u4ea4\u6d41\u9879\u76ee\uff0c\u8fdb\u4e00\u6b65\u63a8\u52a8\u4e2d\u610f\u7535\u5f71\u6587\u5316\u4e4b\u95f4\u7684\u5bf9\u8bdd\u4e0e\u5408\u4f5c\u3002 \u672c\u9879\u76ee\u7531YFCA\u9752\u5e74\u7535\u5f71\u4e0e\u6587\u5316\u534f\u4f1a\u8054\u5408\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\u3001\u8bfa\u5854\u8389\u7ec4\u59d4\u4f1a\u76f8\u5173\u5b66\u672f\u673a\u6784\u53ca\u610f\u5927\u5229\u9a7b\u534e\u5927\u4f7f\u9986\u6587\u5316\u5904\u5171\u540c\u5448\u73b0\u3002 \u653e\u6620\u4fe1\u606f\uff1a 4\u670821\u65e519:00 \u4e07\u8fbe\u5f71\u57ce\uff08\u4e1c\u575d\u4e07\u8fbe\u5e7f\u573a\u6fc0\u5149IMAX\u5e97\uff096\u53f7\u5385 4\u670825\u65e517:00 \u4e07\u8fbe\u5f71\u57ce\uff08\u4e1c\u575d\u4e07\u8fbe\u5e7f\u573a\u6fc0\u5149IMAX\u5e97\uff096\u53f7\u5385 \u552e\u7968\u4fe1\u606f\uff1a \u5b98\u65b9\u6307\u5b9a\u7968\u52a1\u5e73\u53f0\uff1a\u732b\u773c \u5f00\u7968\u65f6\u95f4\uff1a4\u670810\u65e512:00 \u6e29\u99a8\u63d0\u793a\uff1a\u8bf7\u89c2\u4f17\u63d0\u524d\u5728\u732b\u773c\u5e73\u53f0\u201c\u5317\u5f71\u8282\u201d\u4e13\u9898\u9875\u9762\u5b8c\u6210\u5b9e\u540d\u767b\u8bb0\uff0c\u4ee5\u514d\u5f71\u54cd\u8d2d\u7968\u3002<\/p>\n                                <a title=\"\u300a\u827e\u5c14\u8587\u62c9\u00b7\u8bfa\u5854\u8389\uff1a\u4e0d\u518d\u6c89\u5bc2\u300b\u4eae\u76f8\u5317\u4eac\u56fd\u9645\u7535\u5f71\u8282\uff01\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/elvira-notari-beyond-silence-al-beijing-international-film-festival\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/gli-uffizi-di-firenze-dialogo-con-il-direttore-simone-verde\/\" title=\"\u9605\u8bfb\u6587\u7ae0: Gli Uffizi di Firenze &#8211; Dialogo con il Direttore Simone Verde\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Neutral-Traditional-Postcard-from-Florence-Travel-Instagram-Post-240x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Neutral-Traditional-Postcard-from-Florence-Travel-Instagram-Post.jpg 1920w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Neutral-Traditional-Postcard-from-Florence-Travel-Instagram-Post-240x300.jpg 240w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Neutral-Traditional-Postcard-from-Florence-Travel-Instagram-Post-820x1024.jpg 820w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Neutral-Traditional-Postcard-from-Florence-Travel-Instagram-Post-768x960.jpg 768w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\"  title=\"Neutral Traditional Postcard from Florence Travel Instagram Post\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Fri Apr 17 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/gli-uffizi-di-firenze-dialogo-con-il-direttore-simone-verde\/\" title=\"Gli Uffizi di Firenze &#8211; Dialogo con il Direttore Simone Verde\">Gli Uffizi di Firenze &#8211; Dialogo con il Direttore Simone Verde<\/a><\/h5>\n                            <p class=\"card-text\">\u4e0e\u4e4c\u83f2\u5179\u7f8e\u672f\u9986\u7684\u4e00\u573a\u7279\u522b\u5bf9\u8bdd\uff1a\u9986\u957f\u897f\u8499\u5185\u00b7\u5a01\u5c14\u7b2c\u5c06\u5206\u4eab\u4ed6\u5bf9\u535a\u7269\u9986\u672a\u6765\u7684\u613f\u666f\u3001\u9879\u76ee\u4e0e\u53d1\u5c55\u601d\u8def\uff0c\u63a2\u8ba8\u5982\u4f55\u5728\u6587\u5316\u9057\u4ea7\u4fdd\u62a4\u4e0e\u63d0\u5347\u516c\u4f17\u53ef\u53ca\u6027\u4e4b\u95f4\u627e\u5230\u65b0\u7684\u5e73\u8861\uff0c\u5e76\u5e26\u9886\u5927\u5bb6\u56de\u987e\u7f8e\u672f\u9986\u7684\u5386\u53f2\u8109\u7edc\u4e0e\u5f53\u4e0b\u53d1\u5c55\u3002 \u897f\u8499\u5185\u00b7\u5a01\u5c14\u7b2c\uff0c\u7f57\u9a6c\u4eba\uff0c48\u5c81\uff0c\u535a\u7269\u9986\u5b66\u5bb6\u3001\u827a\u672f\u53f2\u5b66\u8005\u30022014\u5e74\u81f32016\u5e74\uff0c\u897f\u8499\u5185\u00b7\u5a01\u5c14\u7b2c\u62c5\u4efb\u963f\u5e03\u624e\u6bd4\u5362\u6d6e\u5bab\u79d1\u7814\u8d1f\u8d23\u4eba\uff1b2016\u5e74\u81f32023\u5e74\uff0c\u51fa\u4efb\u76ae\u6d1b\u5854\u7eaa\u5ff5\u5efa\u7b51\u7fa4\u9986\u957f\uff0c\u5b8c\u6210\u4e86\u8be5\u5efa\u7b51\u7fa4\u7684\u5168\u9762\u4fee\u590d\u4e0e\u91cd\u65b0\u5e03\u5c55\u30022024\u5e74\u88ab\u4efb\u547d\u4e3a\u4e4c\u83f2\u5179\u7f8e\u672f\u9986\u9986\u957f\u3002 \u8fd9\u5c06\u662f\u4e00\u6b21\u96be\u5f97\u7684\u673a\u4f1a\uff0c\u8ba9\u6211\u4eec\u8fd1\u8ddd\u79bb\u4e86\u89e3\u4e4c\u83f2\u5179\u5728\u56fd\u9645\u6587\u5316\u7248\u56fe\u4e2d\u7684\u89d2\u8272\uff0c\u5e76\u5171\u540c\u601d\u8003\u827a\u672f\u5982\u4f55\u6301\u7eed\u4e0e\u5f53\u4ee3\u5bf9\u8bdd\u3002 \u610f\u5927\u5229\u6587\uff0c\u914d\u6709\u4e2d\u6587\u7ffb\u8bd1\u3002<\/p>\n                                <a title=\"Gli Uffizi di Firenze &#8211; Dialogo con il Direttore Simone Verde\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/gli-uffizi-di-firenze-dialogo-con-il-direttore-simone-verde\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/lingua-geniale-umberto-eco-la-semiotica-e-la-progettazione-culturale-nel-dialogo-tra-italia-e-cina\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u5929\u624d\u7684\u8bed\u8a00\uff1a\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Conferencia-sobre-investigacion-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Conferencia-sobre-investigacion-scaled.jpg 1810w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Conferencia-sobre-investigacion-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Conferencia-sobre-investigacion-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Conferencia-sobre-investigacion-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\"  title=\"Conferencia sobre investigaci\u00f3n\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mon Apr 13 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/lingua-geniale-umberto-eco-la-semiotica-e-la-progettazione-culturale-nel-dialogo-tra-italia-e-cina\/\" title=\"\u5929\u624d\u7684\u8bed\u8a00\uff1a\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1\">\u5929\u624d\u7684\u8bed\u8a00\uff1a\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1<\/a><\/h5>\n                            <p class=\"card-text\">2016\u5e742\u670819\u65e5\uff0c\u56fd\u9645\u6587\u5316\u754c\u75db\u5931\u4e00\u4f4d\u602a\u624d\uff1a\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1\u3002 \u4ed6\u53bb\u4e16\u540e\u4e0d\u4e45\uff0c\u4eba\u4eec\u53d1\u73b0\u4ed6\u7684\u9057\u5631\u4e2d\u6709\u4e00\u9879\u6761\u6b3e\uff1a\u5341\u5e74\u5185\uff0c\u4e0d\u5f97\u4e3e\u529e\u4efb\u4f55\u7eaa\u5ff5\u4ed6\u53ca\u5176\u4f5c\u54c1\u7684\u4f1a\u8bae\u3001\u7814\u8ba8\u4f1a\u6216\u5b98\u65b9\u6d3b\u52a8\u3002 \u5982\u4eca\u5341\u5e74\u5df2\u8fc7\uff0c\u6211\u4eec\u7ec8\u4e8e\u53ef\u4ee5\u6253\u7834\u6c89\u9ed8\u3002 \u5728\u610f\u5927\u5229\u5916\u4ea4\u4e0e\u56fd\u9645\u5408\u4f5c\u90e8\u6d3e\u9a7b\u6559\u5e08\u83b1\u8482\u9f50\u4e9a\u00b7\u9c81\u65af\u8482\u51ef\u5229\u6559\u6388\uff08\u73b0\u4efb\u56db\u5ddd\u5916\u56fd\u8bed\u5927\u5b66\u610f\u5927\u5229\u8bed\u8a00\u4e0e\u6587\u5316\u6559\u5e08\uff09\u7684\u5021\u8bae\u4e0b\uff0c\u610f\u5927\u5229\u9a7b\u534e\u4f7f\u9986\u6587\u5316\u4e2d\u5fc3\u548c\u610f\u5927\u5229\u9a7b\u91cd\u5e86\u603b\u9886\u4e8b\u9986\u8054\u5408\u4e3e\u529e\u4e24\u573a\u7cfb\u5217\u7814\u8ba8\u4f1a\uff0c\u65e8\u5728\u63a2\u8ba8\u610f\u5927\u5229\u7b26\u53f7\u5b66\u4f20\u7edf\u4e0b\u7684\u8bed\u8a00\u3001\u521b\u9020\u529b\u548c\u6587\u5316\u8bbe\u8ba1\uff0c\u5e76\u5c06\u5176\u4e0e\u5f53\u4ee3\u4e2d\u56fd\u8bed\u5883\u8fdb\u884c\u5bf9\u8bdd\u3002 \u8fd9\u9879\u6d3b\u52a8\u662f\u5373\u5c06\u4e3e\u884c\u7684\u201c\u4e16\u754c\u610f\u5927\u5229\u8bed\u5468\u201d\u7684\u4e3b\u9898\u9884\u70ed\u3002\u8be5\u6d3b\u52a8\u7531\u610f\u5927\u5229\u76f8\u5173\u90e8\u59d4\uff08\u6587\u5316\u3001\u5a92\u4f53\u548c\u5927\u5b66\u90e8\u4ee5\u53ca\u6587\u5316\u3001\u7814\u7a76\u548c\u521b\u65b0\u90e8\uff09\u8054\u5408\u4e3e\u529e\uff0c\u5c06\u4e8e\u5341\u6708\u4ee5\u201c\u5929\u624d\u7684\u8bed\u8a00\uff1a\u7528\u610f\u5927\u5229\u8bed\u6784\u601d\u3001\u8bbe\u8ba1\u548c\u521b\u9020\u201d\u4e3a\u4e3b\u9898\u3002\u57c3\u79d1\u7684\u4f5c\u54c1\u548c\u601d\u60f3\u582a\u79f0\u201c\u5929\u624d\u7684\u8bed\u8a00\u201d\u7684\u5178\u8303\uff1a\u4e00\u79cd\u80fd\u591f\u6784\u5efa\u590d\u6742\u53d9\u4e8b\u4e16\u754c\u3001\u8de8\u8d8a\u4e0d\u540c\u5a92\u4ecb\u5e76\u50ac\u751f\u7406\u8bba\u548c\u6587\u5316\u521b\u65b0\u7684\u8bed\u8a00\u3002\u4ed6\u5bf9\u8bed\u8a00\u7b26\u53f7\u3001\u8be0\u91ca\u4ee5\u53ca\u4f5c\u8005\u4e0e\u8bfb\u8005\u4e4b\u95f4\u5408\u4f5c\u7684\u601d\u8003\uff0c\u4e3a\u6211\u4eec\u7406\u89e3\u8bed\u8a00\u521b\u9020\u529b\u4f5c\u4e3a\u4e00\u79cd\u8bbe\u8ba1\u5f62\u5f0f\u63d0\u4f9b\u4e86\u91cd\u8981\u7684\u5de5\u5177\u3002 \u672c\u6b21\u8bb2\u5ea7\u5c06\u7279\u522b\u5173\u6ce8\u4ece\u5c0f\u8bf4\u5230\u6f2b\u753b\u7684\u8f6c\u5316\u8fc7\u7a0b\uff0c\u91cd\u70b9\u5206\u6790\u7531\u7c73\u6d1b\u00b7\u9a6c\u7eb3\u62c9\u6839\u636e\u300a\u73ab\u7470\u4e4b\u540d\u300b\u6240\u8fdb\u884c\u7684\u56fe\u50cf\u6539\u7f16\uff0c\u4ee5\u53ca\u8be5\u4f5c\u54c1\u5728\u4e2d\u56fd\u7684\u7ffb\u8bd1\u4e0e\u63a5\u53d7\u60c5\u51b5\u3002\u901a\u8fc7\u8fd9\u4e00\u6848\u4f8b\u7814\u7a76\uff0c\u53ef\u4ee5\u6df1\u5165\u63a2\u8ba8\u6587\u5b57\u4e0e\u56fe\u50cf\u4e4b\u95f4\u7684\u5173\u7cfb\u3001\u8bed\u8a00\u7cfb\u7edf\u4e0e\u56fe\u50cf\u7cfb\u7edf\u4e4b\u95f4\u7684\u5173\u7cfb\uff0c\u4ee5\u53ca\u8de8\u6587\u5316\u7ffb\u8bd1\u7684\u673a\u5236\u3002\u56e0\u6b64\uff0c\u672c\u6b21\u53d1\u8a00\u65e8\u5728\u9610\u660e\u201c\u7ffb\u8bd1\u201d\u6982\u5ff5\u7684\u91cd\u8981\u6027\uff0c\u5e76\u63a2\u8ba8\u5176\u5982\u4f55\u4e0e\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1\u7406\u8bba\u4e0e\u601d\u60f3\u4f53\u7cfb\u4e2d\u7684\u53e6\u4e00\u6838\u5fc3\u6982\u5ff5\u2014\u2014\u201c\u9610\u91ca\u201d\u8fdb\u884c\u5bf9\u6bd4\u3002 \u610f\u5927\u5229\u6587\uff0c\u4e2d\u6587\u7ffb\u8bd1<\/p>\n                                <a title=\"\u5929\u624d\u7684\u8bed\u8a00\uff1a\u7fc1\u8d1d\u6258\u00b7\u57c3\u79d1\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/lingua-geniale-umberto-eco-la-semiotica-e-la-progettazione-culturale-nel-dialogo-tra-italia-e-cina\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-proiezione-del-film-le-vie-dellacqua\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b\">\n                                                                                        <picture>\n                                                <source type=\"image\/webp\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.webp\">\n                                                <source type=\"image\/jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\">\n                                                <img loading=\"lazy\" decoding=\"async\" class=\"img-fluid\" width=\"179\" height=\"125\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\" alt=\"\u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b\" title=\"\u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b\">\n                                            <\/picture>\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Fri Apr 10 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-proiezione-del-film-le-vie-dellacqua\/\" title=\"\u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b\">\u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b<\/a><\/h5>\n                            <p class=\"card-text\">\u5f71\u7247\u300a\u6c34\u4e4b\u9053\u300b\u66fe\u4e8e\u7b2c82\u5c4a\u5a01\u5c3c\u65af\u56fd\u9645\u7535\u5f71\u8282\u975e\u7ade\u8d5b\u5355\u5143\u5c55\u6620\uff0c\u662f\u6b27\u6d32\u7814\u7a76\u7406\u4e8b\u4f1a\uff08ERC\uff09\u9879\u76ee\u201cERC Micoll\u2014\u2014\u5546\u4e1a\u6cd5\u4e0e\u8bed\u8a00\u7684\u8fc1\u79fb\uff1a\u91cd\u65b0\u601d\u8003\u5546\u6cd5\uff0811\u81f317\u4e16\u7eaa\uff09\u201d\u7684\u6210\u679c\u3002\u8be5\u9879\u76ee\u7531\u5e15\u591a\u74e6\u5927\u5b66\u79c1\u6cd5\u4e0e\u6cd5\u5f8b\u6279\u8bc4\u7cfb\u6559\u6388\u65af\u7279\u51e1\u59ae\u5a05\u00b7\u8d3e\u5c14\u5fb7\u7f57\u5c3c\u6784\u601d\u5e76\u534f\u8c03\uff0c\u5979\u540c\u65f6\u4e5f\u662f\u8be5\u6b27\u6d32\u9879\u76ee\u7684\u534f\u8c03\u4eba\u3002 \u5f71\u7247\u7531\u6cd5\u6bd4\u5965\u00b7\u9a6c\u897f\u7f16\u5267\u5e76\u6267\u5bfc\uff0c\u7531Growing Production\u516c\u53f8\u5236\u4f5c\u3002\u5f71\u7247\u8bb2\u8ff0\u4e86\u4e09\u4f4d\u6765\u81ea\u5e15\u591a\u74e6\u8482\u6258\u00b7\u5229\u7ef4\u5965\u9ad8\u4e2d\u7684\u9752\u5c11\u5e74\u5171\u540c\u8e0f\u4e0a\u4e00\u6bb5\u5386\u53f2\u4e4b\u65c5\uff0c\u65e8\u5728\u52a0\u6df1\u4ed6\u4eec\u5bf9\u5373\u5c06\u51fa\u6f14\u7684\u620f\u5267\u89d2\u8272\u7684\u7406\u89e3\u3002\u8fd9\u90e8\u620f\u5267\u6539\u7f16\u81ea\u5361\u6d1b\u00b7\u6208\u5c14\u591a\u5c3c\u7684\u300a\u5546\u4eba\u300b\uff0c\u4f46\u6545\u4e8b\u80cc\u666f\u8bbe\u5b9a\u5728\u5a01\u5c3c\u65af\u5728\u56fd\u9645\u8d38\u6613\u4e2d\u626e\u6f14\u7740\u81f3\u5173\u91cd\u8981\u89d2\u8272\u768415\u4e16\u7eaa\u672b\u81f316\u4e16\u7eaa\u521d\u8fd9\u6bb5\u5173\u952e\u65f6\u671f\u3002\u672c\u4e66\u63a2\u8ba8\u7684\u4e3b\u9898\u2014\u2014\u5546\u4eba\u4f5c\u4e3a\u6587\u5316\u8c03\u89e3\u8005\u7684\u89d2\u8272\u3001\u8bed\u8a00\u969c\u788d\u95ee\u9898\u3001\u4fe1\u4efb\u5728\u7ecf\u6d4e\u5173\u7cfb\u4e2d\u7684\u91cd\u8981\u6027\u3001\u6cd5\u5f8b\u5de5\u5177\u7684\u6f14\u53d8\u2014\u2014\u4e0e\u5e74\u8f7b\u4e3b\u4eba\u516c\u7684\u4eba\u9645\u5173\u7cfb\u52a8\u6001\u4ea4\u7ec7\u5728\u4e00\u8d77\uff0c\u7a81\u663e\u4e86\u5f53\u4eca\u9752\u5c11\u5e74\u65f6\u671f\u7684\u4ef7\u503c\u89c2\u548c\u8106\u5f31\u4e4b\u5904\uff1a\u53cb\u8c0a\u3001\u4e0e\u7236\u6bcd\u7684\u5173\u7cfb\u3001\u7231\u60c5\u7684\u53d1\u73b0\u3002 \u6545\u4e8b\u4e2d\u7684\u4e24\u5ea7\u57ce\u5e02\u5e76\u975e\u4ec5\u4ec5\u662f\u80cc\u666f\uff1a\u5e15\u591a\u74e6\u662f\u4e24\u4f4d\u5e74\u8f7b\u4e3b\u4eba\u516c\u63a5\u53d7\u6559\u80b2\u7684\u5730\u65b9\uff0c\u4f46\u5b83\u672c\u8eab\u4e5f\u662f\u6545\u4e8b\u7684\u4e3b\u89d2\uff0c\u62e5\u6709\u5e7f\u573a\u3001\u8fd0\u6cb3\u548c\u8457\u540d\u7684\u5927\u5b66\u3002\u5a01\u5c3c\u65af\u4e0d\u4ec5\u662f\u8fde\u63a5\u6b27\u6d32\u548c\u9ece\u51e1\u7279\u5730\u533a\u7684\u53e4\u8001\u8d38\u6613\u67a2\u7ebd\uff0c\u800c\u4e14\u5982\u540c\u8fc7\u53bb\u4e00\u6837\uff0c\u81f3\u4eca\u4ecd\u662f\u5404\u79cd\u8bed\u8a00\u548c\u6587\u5316\u7684\u7194\u7089\u3002\u5f71\u7247\u6807\u9898\u4e2d\u8c61\u5f81\u6027\u7684\u201c\u6c34\u201d\u5c06\u8fd9\u4e24\u5ea7\u57ce\u5e02\u7d27\u5bc6\u76f8\u8fde\uff0c\u5b83\u4e0d\u4ec5\u4ee3\u8868\u7740\u4ea4\u901a\u548c\u8d38\u6613\u7684\u7269\u8d28\u57fa\u7840\uff0c\u66f4\u8c61\u5f81\u7740\u6d41\u52a8\u6027\u3001\u8054\u7cfb\u548c\u6587\u5316\u4f20\u627f\u3002 \u8fd9\u90e8\u5f71\u7247\u662f\u7814\u7a76\u7684\u7ed3\u6676\uff0c\u65e8\u5728\u5411\u5e7f\u6cdb\u591a\u5143\u7684\u89c2\u4f17\u7fa4\u4f53\u4f20\u8fbe\u8fd9\u4e00\u8de8\u5b66\u79d1\u9879\u76ee\u7684\u6210\u679c\u3002\u8be5\u9879\u76ee\u6d89\u53ca\u6cd5\u5f8b\u53f2\u3001\u7ecf\u6d4e\u53f2\u548c\u5386\u53f2\u8bed\u8a00\u5b66\u7b49\u9886\u57df\u3002\u5f71\u7247\u7531\u6b27\u76df\u5168\u989d\u8d44\u52a9\u3002\u6b64\u5916\uff0c\u5a01\u5c3c\u65af\u7535\u5f71\u59d4\u5458\u4f1a\u3001\u5a01\u5c3c\u6258\u7535\u5f71\u59d4\u5458\u4f1a\u548c\u610f\u5927\u5229\u822a\u6d77\u534f\u4f1a\u4e5f\u5bf9\u8be5\u9879\u76ee\u7ed9\u4e88\u4e86\u652f\u6301\uff0c\u5e15\u591a\u74e6\u548c\u5a01\u5c3c\u65af\u5e02\u653f\u5e9c\u4e5f\u63d0\u4f9b\u4e86\u534f\u52a9\u3002<\/p>\n                                <a title=\"\u610f\u5927\u5229\u79d1\u7814\u65e5 &#8211; \u7535\u5f71\u653e\u6620\u300a\u6c34\u4e4b\u9053\u300b\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-proiezione-del-film-le-vie-dellacqua\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/%e8%ae%b2%e5%ba%a7-%e7%89%a9%e8%b4%a8%e8%af%ad%e6%b3%95%ef%bc%9a%e8%b4%9d%e4%bc%a6%e6%88%8830%e5%b9%b4%e5%88%9b%e4%bd%9c%e4%bd%93%e7%b3%bb\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u8bb2\u5ea7 &#8211; \u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9-scaled.jpg 1810w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\"  title=\"\u5b57\u7531\u70b9\u5b57\u5339\u558f\u66f9\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Tue Apr 07 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/%e8%ae%b2%e5%ba%a7-%e7%89%a9%e8%b4%a8%e8%af%ad%e6%b3%95%ef%bc%9a%e8%b4%9d%e4%bc%a6%e6%88%8830%e5%b9%b4%e5%88%9b%e4%bd%9c%e4%bd%93%e7%b3%bb\/\" title=\"\u8bb2\u5ea7 &#8211; \u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb\">\u8bb2\u5ea7 &#8211; \u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb<\/a><\/h5>\n                            <p class=\"card-text\">\u8bb2\u5ea7 \u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb \u4e3b\u8bb2\u4eba\uff1a\u5305\u6d2a\u857e\uff0c\u8d1d\u4f26\u6208\u5de5\u4f5c\u5ba4\u8463\u4e8b\u4f1a\u6210\u5458\u3001\u7b56\u5c55\u4eba \u503c\u6b64\u201c\u73bb\u7483\u5e94\u529b\uff1a\u73b0\u4ee3\u827a\u672f\u6f14\u53d8\u5728\u5a01\u5c3c\u65af\u201d\u5c55\u89c8\u5728\u6e05\u534e\u5927\u5b66\u827a\u672f\u535a\u7269\u9986\u4e3e\u529e\u4e4b\u9645\uff0c\u7b56\u5c55\u4eba\u5305\u6d2a\u857e\u5c06\u5e26\u6765\u9898\u4e3a\u300a\u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb\u300b\u7684\u8bb2\u5ea7\uff0c\u56f4\u7ed5Glasstress\u9879\u76ee\uff0c\u6df1\u5165\u63a2\u8ba8\u73bb\u7483\u5982\u4f55\u5728\u5f53\u4ee3\u827a\u672f\u4e2d\u53d1\u5c55\u4e3a\u4e00\u79cd\u5bcc\u6709\u8868\u73b0\u529b\u7684\u521b\u4f5c\u8bed\u8a00\uff0c\u4ee5\u53ca\u5176\u4e09\u5341\u5e74\u6765\u7684\u63a2\u7d22\u4e0e\u5b9e\u8df5\u3002<\/p>\n                                <a title=\"\u8bb2\u5ea7 &#8211; \u7269\u8d28\u8bed\u6cd5\uff1a\u8d1d\u4f26\u620830\u5e74\u521b\u4f5c\u4f53\u7cfb\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/%e8%ae%b2%e5%ba%a7-%e7%89%a9%e8%b4%a8%e8%af%ad%e6%b3%95%ef%bc%9a%e8%b4%9d%e4%bc%a6%e6%88%8830%e5%b9%b4%e5%88%9b%e4%bd%9c%e4%bd%93%e7%b3%bb\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/incontri-con-lopera-aida-2\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u6b4c\u5267\u6709\u7ea6\u7cfb\u5217\u8bb2\u5ea7 \u300a\u963f\u4f9d\u8fbe\u300b\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Green-White-Modern-Aesthetic-Inspirational-Poster-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Green-White-Modern-Aesthetic-Inspirational-Poster-scaled.jpg 1811w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Green-White-Modern-Aesthetic-Inspirational-Poster-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Green-White-Modern-Aesthetic-Inspirational-Poster-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/Green-White-Modern-Aesthetic-Inspirational-Poster-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1811px) 100vw, 1811px\"  title=\"Green White Modern Aesthetic Inspirational Poster\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Thu Apr 02 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/incontri-con-lopera-aida-2\/\" title=\"\u6b4c\u5267\u6709\u7ea6\u7cfb\u5217\u8bb2\u5ea7 \u300a\u963f\u4f9d\u8fbe\u300b\">\u6b4c\u5267\u6709\u7ea6\u7cfb\u5217\u8bb2\u5ea7 \u300a\u963f\u4f9d\u8fbe\u300b<\/a><\/h5>\n                            <p class=\"card-text\">\u5317\u4eac\u610f\u5927\u5229\u9a7b\u534e\u4f7f\u9986\u6587\u5316\u4e2d\u5fc3\u7ee7\u7eed\u4e3e\u529e\u7531\u6731\u585e\u4f69\u00b7\u5e93\u6070\u4e3b\u8bb2\u7684\u6b4c\u5267\u6709\u7ea6\u7cfb\u5217\u8bb2\u5ea7\uff0c\u4ecb\u7ecd\u5373\u5c06\u5728\u5317\u4eac\u56fd\u5bb6\u5927\u5267\u9662\u4e0a\u6f14\u7684\u7ecf\u5178\u6b4c\u5267\u4f5c\u54c1\u3002 4\u67082\u65e5\u665a19:00\uff0c\u6731\u585e\u4f69\u00b7\u5e93\u6070\u5927\u5e08\u5c06\u5e26\u6765\u5173\u4e8e\u5a01\u5c14\u7b2c\u6b4c\u5267\u300a\u963f\u4f9d\u8fbe\u300b\u7684\u8bb2\u5ea7\u3002\u300a\u963f\u4f9d\u8fbe\u300b\u662f\u610f\u5927\u5229\u6b4c\u5267\u6700\u8457\u540d\u7684\u4f5c\u54c1\u4e4b\u4e00\uff0c\u5e76\u5c06\u4e8e4\u67088\u65e5\u81f312\u65e5\u5728\u5317\u4eac\u4e0a\u6f14\u3002 \u5a01\u5c14\u7b2c\u7684\u8fd9\u90e8\u6b4c\u5267\u5c06\u89c2\u4f17\u5e26\u5165\u53e4\u57c3\u53ca\uff0c\u8bb2\u8ff0\u4e86\u57c3\u585e\u4fc4\u6bd4\u4e9a\u5973\u5974\u963f\u4f9d\u8fbe\u4e0e\u57c3\u53ca\u5c06\u9886\u62c9\u8fbe\u6885\u65af\u4e4b\u95f4\u7684\u60b2\u5267\u7231\u60c5\u6545\u4e8b\uff0c\u540c\u65f6\u4e5f\u5c55\u73b0\u4e86\u6cd5\u8001\u4e4b\u5973\u5b89\u5948\u745e\u65af\u7684\u963b\u6320\u4e0e\u51b2\u7a81\u3002\u8be5\u5267\u7531\u57c3\u53ca\u603b\u7763\u59d4\u7ea6\u521b\u4f5c\uff0c\u4ee5\u5e86\u795d\u82cf\u4f0a\u58eb\u8fd0\u6cb3\u7684\u5f00\u901a\uff0c\u5e76\u4e8e1871\u5e74\u5728\u5f00\u7f57\u9996\u6f14\u3002 \u300a\u963f\u4f9d\u8fbe\u300b\u662f\u4e00\u90e8\u7ed3\u6784\u5b8f\u5927\u800c\u60c5\u611f\u7ec6\u817b\u7684\u6770\u4f5c\uff0c\u5728\u5b8f\u4f1f\u58ee\u89c2\u7684\u821e\u53f0\u8868\u73b0\u4e0e\u4eba\u7269\u5185\u5fc3\u7684\u7ec6\u817b\u60c5\u611f\u4e4b\u95f4\u8fbe\u5230\u4e86\u5b8c\u7f8e\u5e73\u8861\u3002\u5176\u97f3\u4e50\u65e2\u6709\u8457\u540d\u800c\u9707\u64bc\u7684\u51ef\u65cb\u8fdb\u884c\u66f2\uff0c\u4e5f\u6709\u4e3b\u4eba\u516c\u5145\u6ee1\u5fe7\u4f24\u4e0e\u67d4\u60c5\u7684\u72ec\u5531\u6bb5\u843d\u3002 \u5267\u4e2d\u5448\u73b0\u4e86\u4e24\u4e2a\u5bf9\u7acb\u6c11\u65cf\u7684\u51b2\u7a81\uff0c\u5374\u6ca1\u6709\u771f\u6b63\u7684\u80dc\u8005\uff0c\u4f7f\u8fd9\u90e8\u539f\u672c\u4e3a\u5e86\u5178\u800c\u521b\u4f5c\u7684\u4f5c\u54c1\u5347\u534e\u4e3a\u5bf9\u4e00\u5207\u6218\u4e89\u7684\u6df1\u523b\u53cd\u601d\uff0c\u5177\u6709\u6781\u5f3a\u7684\u73b0\u5b9e\u610f\u4e49\u3002 \u672c\u6b21\u8bb2\u5ea7\u5c06\u4ee5\u610f\u5927\u5229\u8bed\u8fdb\u884c\uff0c\u5e76\u914d\u6709\u4e2d\u6587\u7ffb\u8bd1\u3002 \u6731\u585e\u4f69\u00b7\u5e93\u6070\uff0c\u56fd\u5bb6\u5927\u5267\u9662\u6b4c\u5267\u827a\u672f\u987e\u95ee\u3002\u6765\u534e\u4e4b\u524d\uff0c\u5e93\u6070\u66fe\u5728\u610f\u5927\u5229\u548c\u5176\u5b83\u56fd\u5bb6\u7684\u8457\u540d\u6b4c\u5267\u9662\u6216\u6b4c\u5267\u8282\u62c5\u4efb\u827a\u672f\u6307\u5bfc\uff08\u5982\uff1a\u5361\u5854\u5c3c\u4e9a\u8d1d\u91cc\u5c3c\u6b4c\u5267\u9662\u3001\u585e\u7ef4\u5229\u4e9a\u201c\u9a6c\u57c3\u65af\u7279\u5170\u8428\u201d\u6b4c\u5267\u9662\u3001\u5df4\u52d2\u83ab\u9a6c\u897f\u83ab\u6b4c\u5267\u9662\u3001\u5361\u5229\u4e9a\u91cc\u6b4c\u5267\u9662\uff0c\u6258\u96f7\u591a\u201c\u57c3\u5c14\u00b7\u683c\u5217\u67ef\u201d\u6b4c\u5267\u8282\u7b49\uff09\u3002\u81ea2011\u5e743\u6708\u8d77\uff0c\u62c5\u4efb\u56fd\u5bb6\u5927\u5267\u9662\u6b4c\u5267\u827a\u672f\u987e\u95ee\u3002<\/p>\n                                <a title=\"\u6b4c\u5267\u6709\u7ea6\u7cfb\u5217\u8bb2\u5ea7 \u300a\u963f\u4f9d\u8fbe\u300b\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/incontri-con-lopera-aida-2\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/presentazione-mostra-ultimate-oneness-type-art-exhibition-di-lorenzo-marini\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u4ecb\u7ecd\u4f1a\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1162706086288845171skey@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715cmmweb_appidwx_webfilehelper-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1162706086288845171skey@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715cmmweb_appidwx_webfilehelper-scaled.jpg 1810w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1162706086288845171skey@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715cmmweb_appidwx_webfilehelper-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1162706086288845171skey@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715cmmweb_appidwx_webfilehelper-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1162706086288845171skey@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715cmmweb_appidwx_webfilehelper-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\"  title=\"_cgi-bin_mmwebwx-bin_webwxgetmsgimg__&#038;MsgID=1162706086288845171&#038;skey=@crypt_56baf4ec_8e74b469c1abf258dbc866713d09715c&#038;mmweb_appid=wx_webfilehelper\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Wed Apr 01 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/presentazione-mostra-ultimate-oneness-type-art-exhibition-di-lorenzo-marini\/\" title=\"\u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u4ecb\u7ecd\u4f1a\">\u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u4ecb\u7ecd\u4f1a<\/a><\/h5>\n                            <p class=\"card-text\">\u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u4ecb\u7ecd\u4f1a 2026.04.01, 19:00 \u610f\u5927\u5229\u4f7f\u9986\u6587\u5316\u4e2d\u5fc3 &nbsp; \u610f\u5927\u5229\u827a\u672f\u5bb6\u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\u5411\u4e2d\u56fd\u89c2\u4f17\u4ecb\u7ecd\u5373\u5c06\u4e8e2026\u5e744\u67082\u65e5\u81f36\u67082\u65e5\u5728\u5317\u4eac\u94f6\u5e1d\u7f8e\u672f\u9986\u5c55\u51fa\u7684\u4e2a\u5c55\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u3002 \u5c55\u89c8\u9898\u76ee\u201c\u4e0a\u4e0a\u5982\u58f9\u201d \u8ba9\u4eba\u8054\u60f3\u5230\u8bed\u8a00\u548c\u4e16\u754c\u89c2\u4e4b\u95f4\u7684\u5bf9\u8bdd\u6982\u5ff5\uff0c\u62c9\u4e01\u5b57\u6bcd\u548c\u4e2d\u56fd\u4e66\u6cd5\u4f20\u7edf\u4e4b\u95f4\u7684\u78b0\u649e\uff0c\u5728\u610f\u5927\u5229\u548c\u4e2d\u56fd\u4e4b\u95f4\u67b6\u8d77\u4e86\u4e00\u5ea7\u89c6\u89c9\u6865\u6881\u3002 &nbsp; \u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff0c\u610f\u5927\u5229\u5f53\u4ee3\u827a\u672f\u5bb6\uff0c\u4ee5\u5176\u5728\u89c6\u89c9\u4f20\u64ad\u9886\u57df\u7684\u521b\u65b0\u65b9\u6cd5\u4ee5\u53ca\u521b\u7acbType Art\uff08\u5b57\u4f53\u827a\u672f\uff09\u8fd0\u52a8\u800c\u95fb\u540d\u3002\u8be5\u827a\u672f\u8fd0\u52a8\u4ee5\u5b57\u6bcd\u4e0e\u6392\u7248\u7684\u8868\u73b0\u529b\u4e3a\u6838\u5fc3\u3002 \u9a6c\u91cc\u5c3c\u66fe\u957f\u671f\u5728\u5e7f\u544a\u754c\u62c5\u4efb\u827a\u672f\u603b\u76d1\u548c\u521b\u610f\u603b\u76d1\u3001\u5e76\u4e0e\u591a\u5bb6\u91cd\u8981\u56fd\u9645\u673a\u6784\u548c\u54c1\u724c\u5408\u4f5c\u3002\u4e4b\u540e\u4ed6\u9010\u6e10\u5c06\u7814\u7a76\u91cd\u5fc3\u8f6c\u5411\u827a\u672f\u521b\u4f5c\uff0c\u5728\u4f5c\u54c1\u4e2d\u5efa\u7acb\u4e86\u8bed\u8a00\u3001\u5ba1\u7f8e\u4e0e\u4fe1\u606f\u4e4b\u95f4\u7684\u7d27\u5bc6\u8054\u7cfb\u3002 \u4ed6\u7684\u4f5c\u54c1\u4ee5\u9c9c\u8273\u7684\u8272\u5f69\u548c\u7b80\u6d01\u7684\u56fe\u5f62\u7b26\u53f7\u4e3a\u7279\u5f81\uff0c\u63a8\u52a8\u4e86\u4e66\u5199\u4f5c\u4e3a\u4e00\u79cd\u72ec\u7acb\u827a\u672f\u5f62\u5f0f\u7684\u91cd\u65b0\u5b9a\u4e49\uff0c\u66fe\u5728\u610f\u5927\u5229\u56fd\u5185\u7684\u7c73\u5170\u3001\u5a01\u5c3c\u65af\u548c\u7f57\u9a6c\u7b49\u5730\uff0c\u4ee5\u53ca\u7ebd\u7ea6\u3001\u6d1b\u6749\u77f6\u3001\u5317\u4eac\u3001\u8fc8\u963f\u5bc6\u548c\u5723\u4fdd\u7f57\u7b49\u56fd\u9645\u91cd\u8981\u57ce\u5e02\u5c55\u51fa\u3002\u76ee\u524d\uff0c\u4ed6\u7684\u4f5c\u54c1\u6b63\u5728\u7f57\u9a6c\u56fd\u7acb\u7f8e\u672f\u9986\u3001\u5e15\u5c14\u9a6c\u76ae\u6d1b\u5854\u7eaa\u5ff5\u5efa\u7b51\u7fa4\u548c\u5317\u4eac\u94f6\u5e1d\u7f8e\u672f\u9986\u5c55\u51fa\u3002\u901a\u8fc7Type Art\uff0c\u9a6c\u91cc\u5c3c\u63a2\u7d22\u5b57\u6bcd\u7684\u60c5\u611f\u4e0e\u8c61\u5f81\u6f5c\u529b\uff0c\u5c06\u5176\u4ece\u529f\u80fd\u6027\u610f\u4e49\u4e2d\u89e3\u653e\u51fa\u6765\uff0c\u8f6c\u5316\u4e3a\u7eaf\u7cb9\u7684\u89c6\u89c9\u8868\u8fbe\u3002<\/p>\n                                <a title=\"\u6d1b\u4f26\u4f50\u00b7\u9a6c\u91cc\u5c3c\uff1a\u201c\u4e0a\u4e0a\u5982\u58f9\u201d\u5b57\u5f62\u89c6\u89c9\u827a\u672f\u5c55\u4ecb\u7ecd\u4f1a\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/presentazione-mostra-ultimate-oneness-type-art-exhibition-di-lorenzo-marini\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/concerto-nacque-al-mondo-un-sole\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u97f3\u4e50\u4f1a\u300a\u4e16\u95f4\u964d\u751f\u4e86\u4e00\u8f6e\u6696\u9633\u300b\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1902608349735697087skey@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ecmmweb_appidwx_webfilehelper-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1902608349735697087skey@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ecmmweb_appidwx_webfilehelper-scaled.jpg 1810w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1902608349735697087skey@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ecmmweb_appidwx_webfilehelper-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1902608349735697087skey@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ecmmweb_appidwx_webfilehelper-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/07\/cgi-bin_mmwebwx-bin_webwxgetmsgimg__MsgID1902608349735697087skey@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ecmmweb_appidwx_webfilehelper-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\"  title=\"_cgi-bin_mmwebwx-bin_webwxgetmsgimg__&#038;MsgID=1902608349735697087&#038;skey=@crypt_56baf4ec_9e3b8bd7d3bb1082c5133c90c35bb6ec&#038;mmweb_appid=wx_webfilehelper\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Fri Mar 27 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/concerto-nacque-al-mondo-un-sole\/\" title=\"\u97f3\u4e50\u4f1a\u300a\u4e16\u95f4\u964d\u751f\u4e86\u4e00\u8f6e\u6696\u9633\u300b\">\u97f3\u4e50\u4f1a\u300a\u4e16\u95f4\u964d\u751f\u4e86\u4e00\u8f6e\u6696\u9633\u300b<\/a><\/h5>\n                            <p class=\"card-text\">\u503c\u6b64\u7eaa\u5ff5\u4e9a\u897f\u897f\u7684\u5723\u65b9\u6d4e\u5404\u901d\u4e16\u516b\u767e\u5468\u5e74\u4e4b\u9645\uff0c\u6211\u4eec\u8363\u5e78\u5730\u9080\u8bf7\u60a8\u51fa\u5e2d\u97f3\u4e50\u4f1a\u300a\u4e16\u95f4\u964d\u751f\u4e86\u4e00\u8f6e\u6696\u9633\u300b\u3002\u97f3\u4e50\u4f1a\u5c06\u4e8e3\u670827\u65e519:00\u5728\u5317\u4eac\u610f\u5927\u5229\u9a7b\u534e\u4f7f\u9986\u6587\u5316\u4e2d\u5fc3\u4e3e\u884c\u3002 \u5c4a\u65f6\uff0c\u5973\u4e2d\u97f3\u6b4c\u5531\u5bb6Valentina Volpe Andreazza\u4e0e\u94a2\u7434\u5bb6Stefano Salvatori\u5c06\u8054\u8882\u6f14\u51fa\u3002 \u672c\u573a\u97f3\u4e50\u4f1a\u901a\u8fc7\u4e00\u4e2a\u8de8\u8d8a\u4e2d\u4e16\u7eaa\u81f3\u5f53\u4ee3\u7684\u97f3\u4e50\u65c5\u7a0b\uff0c\u5448\u73b0\u4eba\u7c7b\u3001\u81ea\u7136\u4e0e\u4e07\u7269\u4e4b\u95f4\u7684\u548c\u8c10\u4e4b\u7f8e\uff0c\u8282\u76ee\u6db5\u76d6\u4e2d\u4e16\u7eaa\u5723\u548f\u3001\u65b9\u6d4e\u5404\u8d5e\u6b4c\u4ee5\u53ca\u6765\u81ea\u4e0d\u540c\u6587\u5316\u4f20\u7edf\u7684\u65cb\u5f8b\u3002 &nbsp; &nbsp; PROGRAMMA Marco Polo Musica di Ennio Morricone Testo di Mauro Morettini e Marco Angelosanti Ni Wen Nel blu dipinto di blu (Volare) Musica di Domenico Modugno Beautiful That Way dal film La vita \u00e8 bella Musica di Nicola Piovani Pianoforte solo \u2013 Musiche da film Ai giochi [&hellip;]<\/p>\n                                <a title=\"\u97f3\u4e50\u4f1a\u300a\u4e16\u95f4\u964d\u751f\u4e86\u4e00\u8f6e\u6696\u9633\u300b\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/concerto-nacque-al-mondo-un-sole\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/italian-design-day-2\/\" title=\"\u9605\u8bfb\u6587\u7ae0: Italian Design Day\">\n                                                                                        <picture>\n                                                <source type=\"image\/webp\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.webp\">\n                                                <source type=\"image\/jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\">\n                                                <img loading=\"lazy\" decoding=\"async\" class=\"img-fluid\" width=\"179\" height=\"125\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/img\/img-default.jpg\" alt=\"Italian Design Day\" title=\"Italian Design Day\">\n                                            <\/picture>\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Tue Mar 10 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/italian-design-day-2\/\" title=\"Italian Design Day\">Italian Design Day<\/a><\/h5>\n                            <p class=\"card-text\">The Italian Design Day (IDD), now in its tenth edition, is the annual thematic initiative launched in 2017 by the Ministry of Foreign Affairs and International Cooperation, in collaboration with and with the support of the Ministry of Culture. The IDD features a wide program of events organized worldwide by the network of Italian Embassies, [&hellip;]<\/p>\n                                <a title=\"Italian Design Day\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/italian-design-day-2\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/mak-grgic-classical-guitar-solo-concert\/\" title=\"\u9605\u8bfb\u6587\u7ae0: \u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947 \u53e4\u5178\u5409\u4ed6\u72ec\u594f\u97f3\u4e50\u4f1a\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/03\/mak-concert-post_page-0001-212x300.jpg\" srcset=\"https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/03\/mak-concert-post_page-0001-scaled.jpg 1810w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/03\/mak-concert-post_page-0001-212x300.jpg 212w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/03\/mak-concert-post_page-0001-724x1024.jpg 724w, https:\/\/iicpechino.esteri.it\/wp-content\/uploads\/2026\/03\/mak-concert-post_page-0001-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\"  title=\"mak concert post_page-0001\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">\u5df2\u7ed3\u675f<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Wed Mar 04 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/mak-grgic-classical-guitar-solo-concert\/\" title=\"\u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947 \u53e4\u5178\u5409\u4ed6\u72ec\u594f\u97f3\u4e50\u4f1a\">\u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947 \u53e4\u5178\u5409\u4ed6\u72ec\u594f\u97f3\u4e50\u4f1a<\/a><\/h5>\n                            <p class=\"card-text\">\u6f14\u51fa\u66f2\u76ee\u5355 \u7ea6\u7ff0\u00b7\u585e\u5df4\u65af\u8482\u5b89\u00b7\u5df4\u8d6b\uff081685\u20131750\uff09 G\u5c0f\u8c03\u7b2c\u4e00\u594f\u9e23\u66f2\uff0cBWV 1001\uff08\u6539\u7f16\u4e3a\u5409\u4ed6\u6f14\u594f\uff09 I. \u67d4\u677f II. \u8d4b\u683c\uff08\u5feb\u677f \uff09 III. \u897f\u897f\u91cc\u821e\u66f2 IV. \u6025\u677f \u83b1\u6602\u00b7\u83f2\u5c14\u65af\u7279 \u4e09\u9996\u65af\u6d1b\u6587\u5c3c\u4e9a\u6c11\u6b4c\uff08\u6539\u7f16\u4e3a\u5409\u4ed6\u6f14\u594f\uff09 \u300a\u9ea6\u7a57\u5df2\u6210\u719f\u300b \u300a\u90a3\u4e9b\u5c0f\u5f84\u5728\u54ea\u91cc\u300b \u300a\u6e05\u6f88\u6eaa\u6d41\u65c1\u7684\u78e8\u574a\u300b \u6069\u5c3c\u5965\u00b7\u83ab\u91cc\u5eb7\u5185\uff081928\u20132020\uff09\uff08\u6539\u7f16\u4e3a\u5409\u4ed6\u6f14\u594f\uff09 \u300a\u52a0\u5e03\u91cc\u57c3\u5c14\u7684\u53cc\u7c27\u7ba1\u300b\uff08\u9009\u81ea\u7535\u5f71\u300a\u6559\u4f1a\u300b \u300a\u9ec4\u91d1\u4e09\u9556\u5ba2\u300b\u4e3b\u9898\u66f2 \u7c73\u7f57\u65af\u62c9\u592b\u00b7\u5854\u8fea\u5947\uff081959\u5e74\u751f\uff09 \u4e09\u9996\u5df4\u5c14\u5e72\u821e\u66f2 \u300aChicho\u300b \u300aJovka\u300b \u300a\u9a6c\u5176\u987f\u5973\u5b69\u300b \u5317\u4eac\u610f\u5927\u5229\u9a7b\u534e\u4f7f\u9986\u6587\u5316\u4e2d\u5fc3\u5c06\u4e8e3\u67084\u65e5\uff08\u661f\u671f\u4e09\uff0919:00\u4e3e\u529e\u4e00\u573a\u7279\u522b\u97f3\u4e50\u4f1a\uff0c\u9080\u8bf7\u65af\u6d1b\u6587\u5c3c\u4e9a\u5409\u4ed6\u6f14\u594f\u5bb6\u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947\u767b\u53f0\u6f14\u51fa\u3002\u672c\u573a\u97f3\u4e50\u4f1a\u662f\u6b27\u76df\u56fd\u5bb6\u6587\u5316\u673a\u6784\u8054\u5408\u4f1a\u9879\u76ee\u4e4b\u4e00\uff0c\u7531\u65af\u6d1b\u6587\u5c3c\u4e9a\u9a7b\u534e\u4f7f\u9986\u4e0e\u6b4c\u5fb7\u5b66\u9662\u5408\u4f5c\u4e3e\u529e\u3002\u97f3\u4e50\u4f1a\u66f2\u76ee\u6db5\u76d6\u591a\u4e2a\u56fd\u5bb6\u7684\u97f3\u4e50\u4f5c\u54c1\uff1a\u4ece\u4e3a\u5409\u4ed6\u7279\u522b\u6539\u7f16\u7684\u5df4\u8d6b\u4f5c\u54c1\uff0c\u5230\u6069\u5c3c\u5965\u00b7\u83ab\u91cc\u5eb7\u5185\u7684\u7535\u5f71\u914d\u4e50\uff0c\u518d\u5230\u83b1\u6602\u00b7\u83f2\u5c14\u65af\u7279\u548c\u7c73\u7f57\u65af\u62c9\u592b\u00b7\u5854\u8fea\u5947\u7684\u65af\u6d1b\u6587\u5c3c\u4e9a\u53ca\u5df4\u5c14\u5e72\u6c11\u95f4\u97f3\u4e50\u3002 \u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947\u662f\u4e00\u4f4d\u66fe\u4e94\u6b21\u83b7\u5f97\u683c\u83b1\u7f8e\u5956\u63d0\u540d\u7684\u5409\u4ed6\u6f14\u594f\u5bb6\u548c\u5531\u7247\u827a\u672f\u5bb6\uff0c\u4ee5\u5176\u591a\u6837\u5316\u7684\u827a\u672f\u98ce\u683c\u548c\u5bcc\u6709\u611f\u67d3\u529b\u7684\u821e\u53f0\u8868\u73b0\u529b\u800c\u5907\u53d7\u8d5e\u8a89\u3002\u300a\u7ebd\u7ea6\u65f6\u62a5\u300b\u79f0\u4ed6\u4e3a\u201c\u624d\u534e\u6a2a\u6ea2\u7684\u5e74\u8f7b\u5409\u4ed6\u6f14\u594f\u5bb6\u201d\uff0c\u300a\u534e\u76db\u987f\u90ae\u62a5\u300b\u5219\u8bc4\u4ef7\u4ed6\u4e3a\u201c\u503c\u5f97\u5173\u6ce8\u7684\u5409\u4ed6\u6f14\u594f\u5bb6\u201d\u3002\u4ed6\u5df2\u6210\u4e3a\u56fd\u9645\u97f3\u4e50\u821e\u53f0\u4e0a\u6781\u5177\u5438\u5f15\u529b\u7684\u6f14\u594f\u8005\u4e4b\u4e00\u3002 \u4ed6\u7684\u66f2\u76ee\u8303\u56f4\u5e7f\u6cdb\uff0c\u4ece\u5df4\u5c14\u5e72\u6c11\u95f4\u97f3\u4e50\u5230\u53e4\u5178\u4f5c\u54c1\uff0c\u518d\u5230\u5fae\u5206\u97f3\u53ca\u5148\u950b\u5f53\u4ee3\u4f5c\u54c1\u30022022\u5e74\uff0c\u4ed6\u9996\u6f14\u4e86\u7535\u5f71\u300a\u9003\u51fa\u7edd\u547d\u9547\u300b\u4f5c\u66f2\u5bb6\u8fc8\u514b\u5c14\u00b7\u963f\u8d1d\u5c14\u65af\u521b\u4f5c\u7684\u4e00\u90e8\u5409\u4ed6\u534f\u594f\u66f2\uff0c\u5e76\u6301\u7eed\u4e0e\u4e16\u754c\u5404\u5730\u7684\u91cd\u8981\u4f5c\u66f2\u5bb6\u5c55\u5f00\u5408\u4f5c\u3002\u683c\u5c14\u5409\u5947\u6bcf\u5e74\u4e3e\u529e\u8fd150\u573a\u97f3\u4e50\u4f1a\uff0c\u6d3b\u8dc3\u4e8e\u4f17\u591a\u77e5\u540d\u573a\u9986\uff0c\u5305\u62ec\u7ebd\u7ea6\u5361\u5185\u57fa\u97f3\u4e50\u5385\u3001\u7ef4\u4e5f\u7eb3\u97f3\u4e50\u534f\u4f1a\u5927\u5385\u3001\u80af\u5c3c\u8fea\u4e2d\u5fc3\u4ee5\u53ca\u9999\u6e2f\u56fd\u9645\u5409\u4ed6\u97f3\u4e50\u8282\u7b49\u3002 \u4f5c\u4e3a\u4e00\u4f4d\u5145\u6ee1\u70ed\u60c5\u7684\u5531\u7247\u827a\u672f\u5bb6\uff0c\u4ed6\u7684\u6700\u65b0\u4e13\u8f91\u300aEntourer\u300b\u2014\u2014\u5411\u65af\u6d1b\u6587\u5c3c\u4e9a\u97f3\u4e50\u81f4\u656c\u2014\u2014\u83b7\u5f97\u683c\u83b1\u7f8e\u5956\u63d0\u540d\u3002\u5176\u4ed6\u5907\u53d7\u597d\u8bc4\u7684\u4e13\u8f91\u8fd8\u5305\u62ec\u300aBalkanisms\u300b\u548c\u300aMAKrotonal\u300b\uff0c\u5176\u4e2d\u540e\u8005\u805a\u7126\u5fae\u5206\u97f3\u97f3\u4e50\uff0c\u5c55\u73b0\u4e86\u4ed6\u5bf9\u5409\u4ed6\u8868\u8fbe\u53ef\u80fd\u6027\u7684\u6301\u7eed\u63a2\u7d22\u3002 \u9664\u4e86\u6f14\u51fa\u4e8b\u4e1a\u5916\uff0c\u683c\u5c14\u5409\u5947\u8fd8\u662f\u4e00\u4f4d\u6559\u80b2\u5bb6\u4e0e\u521b\u4e1a\u8005\uff0c\u521b\u7acb\u4e86\u201c\u865a\u62df\u5409\u4ed6\u4e50\u56e2\u201d\u7b49\u9879\u76ee\uff0c\u6c47\u805a\u5168\u7403\u6570\u5343\u540d\u5409\u4ed6\u6f14\u594f\u8005\u3002\u4ed6\u76ee\u524d\u62c5\u4efb\u5357\u5361\u7f57\u6765\u7eb3\u5927\u5b66\u5168\u804c\u6559\u6388\uff0c\u5e76\u6f14\u594f\u591a\u4f4d\u56fd\u9645\u77e5\u540d\u5236\u7434\u5e08\u5236\u4f5c\u7684\u4e50\u5668\u3002 \u683c\u5c14\u5409\u5947\u7684\u827a\u672f\u8de8\u8d8a\u4f20\u7edf\u4e0e\u97f3\u4e50\u7c7b\u578b\uff0c\u4ee5\u597d\u5947\u5fc3\u3001\u6d3b\u529b\u4e0e\u62d3\u5c55\u5409\u4ed6\u827a\u672f\u8fb9\u754c\u7684\u4f7f\u547d\u611f\u4e3a\u9a71\u52a8\u529b\uff0c\u5728\u4e0d\u540c\u6587\u5316\u4e4b\u95f4\u67b6\u8d77\u6865\u6881\u3002<\/p>\n                                <a title=\"\u9a6c\u514b\u00b7\u683c\u5c14\u5409\u5947 \u53e4\u5178\u5409\u4ed6\u72ec\u594f\u97f3\u4e50\u4f1a\" class=\"read-more\" href=\"https:\/\/iicpechino.esteri.it\/zh\/gli_eventi\/calendario\/mak-grgic-classical-guitar-solo-concert\/\">\n                                    <span class=\"text\">\u67e5\u770b\u66f4\u591a<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">\u5206\u9875<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/?pag=63\">63<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/iicpechino.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">\u4e0b\u4e00\u9875<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp;","protected":false},"author":1,"featured_media":0,"parent":37,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2522","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/comments?post=2522"}],"version-history":[{"count":1,"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/revisions"}],"predecessor-version":[{"id":2699,"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/2522\/revisions\/2699"}],"up":[{"embeddable":true,"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/pages\/37"}],"wp:attachment":[{"href":"https:\/\/iicpechino.esteri.it\/zh\/wp-json\/wp\/v2\/media?parent=2522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}